{"id":2552,"date":"2026-05-13T09:14:30","date_gmt":"2026-05-13T09:14:30","guid":{"rendered":"https:\/\/jornalfc.com\/?p=2552"},"modified":"2026-05-13T09:14:30","modified_gmt":"2026-05-13T09:14:30","slug":"lula-assina-mp-e-zera-taxa-das-blusinhas","status":"publish","type":"post","link":"https:\/\/jornalfc.com\/pt\/2026\/05\/13\/lula-assina-mp-e-zera-taxa-das-blusinhas\/","title":{"rendered":"Lula assina MP e zera &#8220;taxa das blusinhas&#8221;"},"content":{"rendered":"<p>Cobran\u00e7a em compras de at\u00e9 US$ 50 estava em vigor desde 2024<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"479\" src=\"https:\/\/jornalfc.com\/wp-content\/uploads\/2026\/05\/Sem-Titulo-1.jpg\" alt=\"\" class=\"wp-image-2553\" style=\"aspect-ratio:1.6701932571589786;width:718px;height:auto\" srcset=\"https:\/\/jornalfc.com\/wp-content\/uploads\/2026\/05\/Sem-Titulo-1.jpg 800w, https:\/\/jornalfc.com\/wp-content\/uploads\/2026\/05\/Sem-Titulo-1-300x180.jpg 300w, https:\/\/jornalfc.com\/wp-content\/uploads\/2026\/05\/Sem-Titulo-1-768x460.jpg 768w, https:\/\/jornalfc.com\/wp-content\/uploads\/2026\/05\/Sem-Titulo-1-18x12.jpg 18w, https:\/\/jornalfc.com\/wp-content\/uploads\/2026\/05\/Sem-Titulo-1-590x354.jpg 590w, https:\/\/jornalfc.com\/wp-content\/uploads\/2026\/05\/Sem-Titulo-1-400x240.jpg 400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>O presidente Luiz In\u00e1cio Lula da Silva assinou, nesta ter\u00e7a-feira (12), uma Medida Provis\u00f3ria (MP) para acabar com a cobran\u00e7a de 20% de Imposto de Importa\u00e7\u00e3o sobre compras internacionais de at\u00e9 US$ 50, apelidada de &#8220;taxa das blusinhas\u201d.&nbsp;<\/p>\n\n\n\n<p>A Medida Provis\u00f3ria deve ser publicada em edi\u00e7\u00e3o extraordin\u00e1ria do Di\u00e1rio Oficial ainda hoje.<\/p>\n\n\n\n<p>No ato de assinatura oficial, o secret\u00e1rio executivo do Minist\u00e9rio da Fazenda, Rog\u00e9rio Ceron, explicou que foi poss\u00edvel zerar o imposto ap\u00f3s tr\u00eas anos de combate ao contrabando e maior regulariza\u00e7\u00e3o do setor.<\/p>\n\n\n\n<p>\u201cO contrabando, que era uma marca presente nesse setor, foi eliminado. Agora, o setor regularizado vai poder usufruir dessa isen\u00e7\u00e3o sobre esses produtos\u201d, afirmou.<\/p>\n\n\n\n<p>Para o secret\u00e1rio, a decis\u00e3o vai beneficiar a popula\u00e7\u00e3o de baixa renda que utiliza plataformas para adquirir produtos.<\/p>\n\n\n\n<p><strong>&#8220;N\u00e3o \u00e9 s\u00f3 blusinha&#8221;<\/strong><\/p>\n\n\n\n<p>A ministra da Casa Civil, Miriam Belchior, destacou que, apesar do apelido, as compras internacionais desse valor s\u00e3o diversificadas, n\u00e3o apenas de roupas.<\/p>\n\n\n\n<p>\u201cN\u00e3o \u00e9 s\u00f3 roupa. H\u00e1 um conjunto de outros bens que s\u00e3o comprados, todos de valor pequeno\u201d, afirmou.<\/p>\n\n\n\n<p>O ministro do Planejamento e Or\u00e7amento, Bruno Moretti, afirmou que zerar as taxas federais dessas compras melhora o perfil da nossa tributa\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u201cOs n\u00fameros mostram que a maior parte das compras, de fato, \u00e9 de baixo valor. Est\u00e1 associado ao consumo popular\u201d.<\/p>\n\n\n\n<p>A chamada &#8220;taxa das blusinhas&#8221; entrou em vigor em agosto de 2024, dentro do programa \u201cRemessa Conforme\u201d, criado para regulamentar o com\u00e9rcio eletr\u00f4nico internacional.<\/p>\n\n\n\n<p>Na pr\u00e1tica, o imposto era cobrado no momento da compra, para aumentar a fiscaliza\u00e7\u00e3o e a redu\u00e7\u00e3o de fraudes. Ag\u00eancia Brasil<\/p>","protected":false},"excerpt":{"rendered":"<p>Cobran\u00e7a em compras de at\u00e9 US$ 50 estava em vigor desde 2024 O presidente Luiz In\u00e1cio Lula da Silva assinou, nesta ter\u00e7a-feira (12), uma Medida Provis\u00f3ria (MP) para acabar com a cobran\u00e7a de 20% de Imposto de Importa\u00e7\u00e3o sobre compras internacionais de at\u00e9 US$ 50, apelidada de &#8220;taxa das blusinhas\u201d.&nbsp; A Medida Provis\u00f3ria deve ser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[20,22],"tags":[],"class_list":["post-2552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-economia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/posts\/2552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/comments?post=2552"}],"version-history":[{"count":1,"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/posts\/2552\/revisions"}],"predecessor-version":[{"id":2554,"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/posts\/2552\/revisions\/2554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/media\/2553"}],"wp:attachment":[{"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/media?parent=2552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/categories?post=2552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalfc.com\/pt\/wp-json\/wp\/v2\/tags?post=2552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}